{"id":697,"count":12,"description":"OLIMP Sport Nutrition Supplements and Products at Muscle A&amp;R Madness Quality Supplement Store for athletes and sportsmen, established in Poland.","link":"https:\/\/www.muscle-madness.co.uk\/store\/product-category\/brands\/olimp\/","name":"OLIMP Sport Nutrition","slug":"olimp","taxonomy":"product_cat","parent":154,"meta":[],"menu_order":15,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OLIMP Sport Nutrition Archives - Muscle and Madness Supplement Store<\/title>\n<meta name=\"description\" content=\"OLIMP Sport Nutrition Supplements and Products at Muscle A&amp;R Madness Quality Supplement Store for athletes and sportsmen, established in Poland.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.muscle-madness.co.uk\/store\/product-category\/brands\/olimp\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OLIMP Sport Nutrition Archives - Muscle and Madness Supplement Store\" \/>\n<meta property=\"og:description\" content=\"OLIMP Sport Nutrition Supplements and Products at Muscle A&amp;R Madness Quality Supplement Store for athletes and sportsmen, established in Poland.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.muscle-madness.co.uk\/store\/product-category\/brands\/olimp\/\" \/>\n<meta property=\"og:site_name\" content=\"Muscle and Madness Supplement Store\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.muscle-madness.co.uk\\\/store\\\/product-category\\\/brands\\\/olimp\\\/\",\"url\":\"https:\\\/\\\/www.muscle-madness.co.uk\\\/store\\\/product-category\\\/brands\\\/olimp\\\/\",\"name\":\"OLIMP Sport Nutrition Archives - Muscle and Madness Supplement Store\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.muscle-madness.co.uk\\\/store\\\/#website\"},\"description\":\"OLIMP Sport Nutrition Supplements and Products at Muscle A&R Madness Quality Supplement Store for athletes and sportsmen, established in Poland.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.muscle-madness.co.uk\\\/store\\\/product-category\\\/brands\\\/olimp\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.muscle-madness.co.uk\\\/store\\\/product-category\\\/brands\\\/olimp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.muscle-madness.co.uk\\\/store\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BRANDS\",\"item\":\"https:\\\/\\\/www.muscle-madness.co.uk\\\/store\\\/product-category\\\/brands\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"OLIMP Sport Nutrition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.muscle-madness.co.uk\\\/store\\\/#website\",\"url\":\"https:\\\/\\\/www.muscle-madness.co.uk\\\/store\\\/\",\"name\":\"Muscle and Madness Supplement Store\",\"description\":\"Suplement Store\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.muscle-madness.co.uk\\\/store\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OLIMP Sport Nutrition Archives - Muscle and Madness Supplement Store","description":"OLIMP Sport Nutrition Supplements and Products at Muscle A&R Madness Quality Supplement Store for athletes and sportsmen, established in Poland.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.muscle-madness.co.uk\/store\/product-category\/brands\/olimp\/","og_locale":"en_US","og_type":"article","og_title":"OLIMP Sport Nutrition Archives - Muscle and Madness Supplement Store","og_description":"OLIMP Sport Nutrition Supplements and Products at Muscle A&R Madness Quality Supplement Store for athletes and sportsmen, established in Poland.","og_url":"https:\/\/www.muscle-madness.co.uk\/store\/product-category\/brands\/olimp\/","og_site_name":"Muscle and Madness Supplement Store","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.muscle-madness.co.uk\/store\/product-category\/brands\/olimp\/","url":"https:\/\/www.muscle-madness.co.uk\/store\/product-category\/brands\/olimp\/","name":"OLIMP Sport Nutrition Archives - Muscle and Madness Supplement Store","isPartOf":{"@id":"https:\/\/www.muscle-madness.co.uk\/store\/#website"},"description":"OLIMP Sport Nutrition Supplements and Products at Muscle A&R Madness Quality Supplement Store for athletes and sportsmen, established in Poland.","breadcrumb":{"@id":"https:\/\/www.muscle-madness.co.uk\/store\/product-category\/brands\/olimp\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.muscle-madness.co.uk\/store\/product-category\/brands\/olimp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.muscle-madness.co.uk\/store\/"},{"@type":"ListItem","position":2,"name":"BRANDS","item":"https:\/\/www.muscle-madness.co.uk\/store\/product-category\/brands\/"},{"@type":"ListItem","position":3,"name":"OLIMP Sport Nutrition"}]},{"@type":"WebSite","@id":"https:\/\/www.muscle-madness.co.uk\/store\/#website","url":"https:\/\/www.muscle-madness.co.uk\/store\/","name":"Muscle and Madness Supplement Store","description":"Suplement Store","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.muscle-madness.co.uk\/store\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.muscle-madness.co.uk\/store\/wp-json\/wp\/v2\/product_cat\/697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muscle-madness.co.uk\/store\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.muscle-madness.co.uk\/store\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.muscle-madness.co.uk\/store\/wp-json\/wp\/v2\/product_cat\/154"}],"wp:post_type":[{"href":"https:\/\/www.muscle-madness.co.uk\/store\/wp-json\/wp\/v2\/product?product_cat=697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}